{"id":292,"count":1,"description":"","link":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/tag\/abstract-expressionism\/","name":"abstract expressionism","slug":"abstract-expressionism","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/tag\/abstract-expressionism\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/292\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/tag\\\/abstract-expressionism\\\/#listItem\",\"name\":\"abstract expressionism\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/tag\\\/abstract-expressionism\\\/#listItem\",\"position\":2,\"name\":\"abstract expressionism\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/292\\\/#collectionpage\",\"url\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/292\\\/\",\"name\":\"abstract expressionism - Voice of London\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/292\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/#organization\",\"name\":\"Voice of London\",\"description\":\"News for young Londoners\",\"url\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/#website\",\"url\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/\",\"name\":\"Voice of London\",\"description\":\"News for young Londoners\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.westminster.ac.uk\\\/thevoiceoflondon\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"abstract expressionism - Voice of London","description":"","canonical_url":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/tag\/abstract-expressionism\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/tags\/292\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon#listItem","position":1,"name":"Home","item":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/tag\/abstract-expressionism\/#listItem","name":"abstract expressionism"}},{"@type":"ListItem","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/tag\/abstract-expressionism\/#listItem","position":2,"name":"abstract expressionism","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/tags\/292\/#collectionpage","url":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/tags\/292\/","name":"abstract expressionism - Voice of London","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/#website"},"breadcrumb":{"@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/tags\/292\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/#organization","name":"Voice of London","description":"News for young Londoners","url":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/"},{"@type":"WebSite","@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/#website","url":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/","name":"Voice of London","description":"News for young Londoners","inLanguage":"en-GB","publisher":{"@id":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tabstract expressionism\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon"},{"label":"abstract expressionism","link":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/tag\/abstract-expressionism\/"}],"_links":{"self":[{"href":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/tags\/292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.westminster.ac.uk\/thevoiceoflondon\/wp-json\/wp\/v2\/posts?tags=292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}